{"id":3,"date":"2025-06-03T00:04:54","date_gmt":"2025-06-03T00:04:54","guid":{"rendered":"http:\/\/salvaguardaycultura.org\/?page_id=3"},"modified":"2026-08-19T20:38:04","modified_gmt":"2026-08-19T20:38:04","slug":"privacy-policy-2","status":"publish","type":"page","link":"https:\/\/salvaguardaycultura.org\/en\/privacy-policy-2\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<h2 class=\"wp-block-heading\">About Us<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La direcci\u00f3n de nuestro sitio web es: http:\/\/salvaguardaycultura.org.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comentarios<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando los visitantes dejan comentarios en el sitio, recopilamos los datos que aparecen en el formulario de comentarios, as\u00ed como la direcci\u00f3n IP del visitante y la cadena de agente de usuario del navegador para ayudar a detectar el spam.\n\nEs posible que se proporcione al servicio Gravatar una cadena an\u00f3nima creada a partir de tu direcci\u00f3n de correo electr\u00f3nico (tambi\u00e9n llamada *hash*) para comprobar si utilizas dicho servicio. La pol\u00edtica de privacidad del servicio Gravatar est\u00e1 disponible aqu\u00ed: https:\/\/automattic.com\/privacy\/. Una vez aprobado tu comentario, tu foto de perfil ser\u00e1 visible para el p\u00fablico en el contexto de tu comentario.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Medios<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si subes im\u00e1genes al sitio web, deber\u00edas evitar subir im\u00e1genes que contengan datos de ubicaci\u00f3n incrustados (EXIF GPS). Los visitantes del sitio web pueden descargar y extraer cualquier dato de ubicaci\u00f3n de las im\u00e1genes presentes en el sitio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si dejas un comentario en nuestro sitio, puedes optar por guardar tu nombre, direcci\u00f3n de correo electr\u00f3nico y sitio web en cookies. Esto se hace para tu comodidad, de modo que no tengas que volver a rellenar tus datos cuando dejes otro comentario. Estas cookies tienen una duraci\u00f3n de un a\u00f1o.<br><br>Si visitas nuestra p\u00e1gina de inicio de sesi\u00f3n, estableceremos una cookie temporal para determinar si tu navegador acepta cookies. Esta cookie no contiene datos personales y se elimina al cerrar el navegador.<br><br>Cuando inicias sesi\u00f3n, tambi\u00e9n configuramos varias cookies para guardar tu informaci\u00f3n de inicio de sesi\u00f3n y tus opciones de visualizaci\u00f3n de pantalla. Las cookies de inicio de sesi\u00f3n duran dos d\u00edas y las cookies de opciones de pantalla duran un a\u00f1o. Si seleccionas &#8220;Recu\u00e9rdame&#8221;, tu inicio de sesi\u00f3n se mantendr\u00e1 durante dos semanas. Si cierras sesi\u00f3n en tu cuenta, las cookies de inicio de sesi\u00f3n se eliminar\u00e1n.<br><br>Si editas o publicas un art\u00edculo, se guardar\u00e1 una cookie adicional en tu navegador. Esta cookie no incluye datos personales y simplemente indica el ID de la publicaci\u00f3n que acabas de editar. Caduca despu\u00e9s de 1 d\u00eda.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contenido Incrustrado de otros sitios web<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos de este sitio pueden incluir contenido incrustado (por ejemplo, v\u00eddeos, im\u00e1genes, art\u00edculos, etc.). El contenido incrustado de otros sitios web se comporta exactamente de la misma manera que si el visitante hubiera visitado el otro sitio web.\n\nEstos sitios web pueden recopilar datos sobre ti, utilizar cookies, incrustar un seguimiento adicional de terceros y supervisar tu interacci\u00f3n con ese contenido incrustado, incluido el seguimiento de tu interacci\u00f3n con el contenido incrustado si tienes una cuenta y has iniciado sesi\u00f3n en ese sitio web.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Con qui\u00e9n compartimos tus datos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si solicitas un restablecimiento de contrase\u00f1a, tu direcci\u00f3n IP se incluir\u00e1 en el correo electr\u00f3nico de restablecimiento.\n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cu\u00e1nto tiempo conservamos tus datos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si dejas un comentario, el comentario y sus metadatos se conservan indefinidamente. Esto nos permite reconocer y aprobar autom\u00e1ticamente cualquier comentario posterior, en lugar de mantenerlos en una cola de moderaci\u00f3n.\n\nPara los usuarios que se registran en nuestro sitio web (si los hay), tambi\u00e9n almacenamos la informaci\u00f3n personal que proporcionan en su perfil de usuario. Todos los usuarios pueden ver, editar o eliminar su informaci\u00f3n personal en cualquier momento (excepto que no pueden cambiar su nombre de usuario). Los administradores del sitio web tambi\u00e9n pueden ver y editar esa informaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Que derechos tienes sobre tus datos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Si tienes una cuenta en este sitio o has dejado comentarios, puedes solicitar recibir un archivo de exportaci\u00f3n con los datos personales que tenemos sobre ti, incluidos los datos que nos hayas proporcionado. Tambi\u00e9n puedes solicitar que eliminemos cualquier dato personal que tengamos sobre ti. Esto no incluye los datos que estemos obligados a conservar con fines administrativos, legales o de seguridad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Donde se env\u00e1n tus datos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los comentarios de los visitantes pueden ser revisados \u200b\u200bmediante un servicio de detecci\u00f3n autom\u00e1tica de spam.<\/p>","protected":false},"excerpt":{"rendered":"<p>Qui\u00e9nes Somos La direcci\u00f3n de nuestro sitio web es: http:\/\/salvaguardaycultura.org. Comentarios Cuando los visitantes dejan comentarios en el sitio, recopilamos los datos que aparecen en el formulario de comentarios, as\u00ed como la direcci\u00f3n IP del visitante y la cadena de agente de usuario del navegador para ayudar a detectar el spam. Es posible que se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"blocksy_meta":[],"aioseo_notices":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"salvaguarda.cultura@gmail.com","author_link":"https:\/\/salvaguardaycultura.org\/en\/author\/salvaguarda-culturagmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Qui\u00e9nes Somos La direcci\u00f3n de nuestro sitio web es: http:\/\/salvaguardaycultura.org. Comentarios Cuando los visitantes dejan comentarios en el sitio, recopilamos los datos que aparecen en el formulario de comentarios, as\u00ed como la direcci\u00f3n IP del visitante y la cadena de agente de usuario del navegador para ayudar a detectar el spam. Es posible que se&hellip;","_links":{"self":[{"href":"https:\/\/salvaguardaycultura.org\/en\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salvaguardaycultura.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/salvaguardaycultura.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/salvaguardaycultura.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/salvaguardaycultura.org\/en\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":1,"href":"https:\/\/salvaguardaycultura.org\/en\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":1527,"href":"https:\/\/salvaguardaycultura.org\/en\/wp-json\/wp\/v2\/pages\/3\/revisions\/1527"}],"wp:attachment":[{"href":"https:\/\/salvaguardaycultura.org\/en\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}